{"id":16021,"date":"2026-03-13T05:37:23","date_gmt":"2026-03-13T04:37:23","guid":{"rendered":"https:\/\/menardcanada.ca\/?p=16021"},"modified":"2026-04-16T23:17:55","modified_gmt":"2026-04-16T21:17:55","slug":"ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets","status":"publish","type":"post","link":"https:\/\/menardcanada.ca\/fr\/ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets\/","title":{"rendered":"Ground Talk Ontario 2026 : Une salle comble, des \u00e9changes riches et des enseignements concrets"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container fusion-parallax-none nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:150px;--awb-padding-bottom:90px;--awb-padding-top-medium:80px;--awb-background-color:#ebebeb;--awb-background-image:linear-gradient(180deg, #ebebeb 0%,#c3c3c3 100%),url(https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2021\/05\/Vibrocompaction_La-Mer_dubai_Menard-2-scaled.jpg);;--awb-background-size:cover;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"max-width:1216.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_2_3 2_3 fusion-flex-column\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-width-large:66.666666666667%;--awb-margin-top-large:0px;--awb-spacing-right-large:2.88%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:2.88%;--awb-width-medium:75%;--awb-spacing-right-medium:2.56%;--awb-spacing-left-medium:2.56%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>Lecture de 3 minutes<\/p>\n<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-image-element\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"1140\" height=\"200\" title=\"Untitled design (2)\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Untitled-design-2.png\" alt class=\"img-responsive wp-image-16029\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Untitled-design-2-200x35.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Untitled-design-2-400x70.png 400w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Untitled-design-2-600x105.png 600w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Untitled-design-2-800x140.png 800w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Untitled-design-2.png 1140w\" sizes=\"(max-width: 1200px) 100vw, (max-width: 1024px) 100vw, 800px\" \/><\/span><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_2_3 2_3 fusion-flex-column\" style=\"--awb-padding-top:50px;--awb-padding-right:50px;--awb-padding-bottom:50px;--awb-padding-left:50px;--awb-bg-color:#ffffff;--awb-bg-color-hover:#ffffff;--awb-bg-size:cover;--awb-border-color:#e20025;--awb-border-bottom:8px;--awb-border-style:solid;--awb-width-large:66.666666666667%;--awb-margin-top-large:0px;--awb-spacing-right-large:2.88%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:2.88%;--awb-width-medium:75%;--awb-order-medium:0;--awb-spacing-right-medium:2.56%;--awb-spacing-left-medium:2.56%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-2\"><div class=\"x_elementToProof\">\n<p><a href=\"https:\/\/menardcanada.ca\/fr\/ground-talk-managing-challenging-sites-and-new-regulations-in-ontario\/\">Le 5 mars 2026<\/a>, l\u2019\u00e9quipe ontarienne de Menard Canada a accueilli plus de 150 professionnels \u00e0 l\u2019occasion de <a href=\"https:\/\/menardcanada.ca\/fr\/ground-talk-managing-challenging-sites-and-new-regulations-in-ontario\/\">\u00ab Ground Talk Ontario : G\u00e9rer les chantiers difficiles et les nouvelles r\u00e9glementations \u00bb<\/a> \u2014 une formation d\u2019une journ\u00e9e enti\u00e8re articul\u00e9e autour d\u2019une id\u00e9e centrale : r\u00e9unir les bonnes personnes pour mener des discussions pratiques et franches sur les contraintes actuelles li\u00e9es aux projets.<\/p>\n<p>Si vous \u00e9tiez pr\u00e9sent, vous l\u2019avez ressenti.<\/p>\n<p>Si vous n\u2019y \u00e9tiez pas, voici ce qui a marqu\u00e9 cette journ\u00e9e.<\/p>\n<\/div>\n<\/div><div class=\"fusion-image-element\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-2 hover-type-none\"><img decoding=\"async\" width=\"800\" height=\"600\" title=\"Image (48)\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-48.jpg\" alt class=\"img-responsive wp-image-16033\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-48-200x150.jpg 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-48-400x300.jpg 400w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-48-600x450.jpg 600w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-48.jpg 800w\" sizes=\"(max-width: 1200px) 100vw, (max-width: 1024px) 100vw, 800px\" \/><\/span><\/div><div class=\"fusion-text fusion-text-3\"><h3 class=\"fusion-responsive-typography-calculated\" style=\"--fontsize: 20;line-height: 1.4;--minfontsize: 20\" data-fontsize=\"20\" data-lineheight=\"28px\"><strong>Une formation ax\u00e9e sur l\u2019essentiel<\/strong><\/h3>\n<div class=\"x_elementToProof\">\n<p>Ground Talk Ontario a \u00e9t\u00e9 con\u00e7u autour de d\u00e9fis r\u00e9els li\u00e9s aux projets.<\/p>\n<p>Parmi les th\u00e8mes cl\u00e9s figuraient :<\/p>\n<ul>\n<li>l&rsquo;\u00e9volution des cadres r\u00e9glementaires et la gestion des exc\u00e9dents de terre<\/li>\n<li>les mises \u00e0 jour sismiques et leur impact sur la conception des fondations<\/li>\n<li>les lacunes de coordination entre les disciplines<\/li>\n<li>les attentes des ma\u00eetres d&rsquo;ouvrage, les risques et les autorisations<\/li>\n<li>les strat\u00e9gies <a href=\"https:\/\/menardcanada.ca\/fr\/profil\/amelioration-du-sol\/\">d&rsquo;am\u00e9lioration des sols<\/a><\/li>\n<li><a href=\"https:\/\/menardcanada.ca\/fr\/ethique\/developpement-durable\/\">la durabilit\u00e9<\/a> et le carbone incorpor\u00e9 sous le niveau du sol<\/li>\n<\/ul>\n<p>Les discussions ont port\u00e9 sur la prise de d\u00e9cision pratique, et sur la mani\u00e8re dont les \u00e9quipes s&rsquo;alignent plus t\u00f4t pour r\u00e9duire les risques, les retards et l&rsquo;incertitude.<\/p>\n<p>L&rsquo;objectif est rest\u00e9 clair tout au long de la journ\u00e9e : comment les d\u00e9cisions prises en amont concernant les sols influencent les co\u00fbts, les risques et la constructibilit\u00e9.<\/p>\n<\/div>\n<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-slider-sc\"><div class=\"fusion-flexslider-loading flexslider flexslider-hover-type-liftup\" data-slideshow_autoplay=\"1\" data-slideshow_smooth_height=\"1\" data-slideshow_speed=\"5050\" style=\"max-width:100%;height:100%;\"><ul class=\"slides\"><li class=\"image\"><span class=\"fusion-image-hover-element hover-type-liftup\"><img decoding=\"async\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-4-scaled.jpg\" width=\"2560\" height=\"1920\" class=\"wp-image-16065\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-4-200x150.jpg 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-4-400x300.jpg 400w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-4-600x450.jpg 600w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-4-800x600.jpg 800w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-4-1200x900.jpg 1200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-4-scaled.jpg 2560w\" sizes=\"(max-width: 1200px) 100vw, (max-width: 1024px) 100vw, 800px\" \/><\/span><\/li><li class=\"image\"><span class=\"fusion-image-hover-element hover-type-liftup\"><img decoding=\"async\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-40-scaled.jpg\" width=\"2560\" height=\"1920\" class=\"wp-image-16047\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-40-200x150.jpg 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-40-400x300.jpg 400w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-40-600x450.jpg 600w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-40-800x600.jpg 800w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-40-1200x900.jpg 1200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-40-scaled.jpg 2560w\" sizes=\"(max-width: 1200px) 100vw, (max-width: 1024px) 100vw, 800px\" \/><\/span><\/li><li class=\"image\"><span class=\"fusion-image-hover-element hover-type-liftup\"><img decoding=\"async\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-46-scaled.jpg\" width=\"2560\" height=\"1920\" class=\"wp-image-16035\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-46-200x150.jpg 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-46-400x300.jpg 400w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-46-600x450.jpg 600w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-46-800x600.jpg 800w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-46-1200x900.jpg 1200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-46-scaled.jpg 2560w\" sizes=\"(max-width: 1200px) 100vw, (max-width: 1024px) 100vw, 800px\" \/><\/span><\/li><\/ul><\/div><\/div><div class=\"fusion-text fusion-text-4\" style=\"--awb-content-alignment:left;\"><h3><strong>Une conversation interdisciplinaire<\/strong><\/h3>\n<p>Ce qui a donn\u00e9 tout son impact \u00e0 cet \u00e9v\u00e9nement, c&rsquo;est la diversit\u00e9 des points de vue r\u00e9unis dans la salle.<\/p>\n<p>Ing\u00e9nieurs, architectes, entrepreneurs, promoteurs, propri\u00e9taires et repr\u00e9sentants du secteur public se sont retrouv\u00e9s dans un m\u00eame espace, refl\u00e9tant ainsi la r\u00e9alit\u00e9 de la mise en \u0153uvre des projets : une approche interdisciplinaire, des risques partag\u00e9s et une pression croissante pour une coordination pr\u00e9coce.<\/p>\n<p>Cette diversit\u00e9 n&rsquo;a pas seulement rempli la salle. Elle a enrichi les discussions.<\/p>\n<p>Les conversations se sont poursuivies tout au long de la journ\u00e9e, soutenues par des moments interactifs tels que le quiz Kahoot et les pauses de r\u00e9seautage. Un don \u00e0 Habitat pour l\u2019humanit\u00e9 GTA a mis en \u00e9vidence l\u2019impact plus large du travail de l\u2019industrie sur les communaut\u00e9s locales.<\/p>\n<\/div><div class=\"fusion-image-element\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-3 hover-type-none\"><img decoding=\"async\" width=\"2560\" height=\"1440\" title=\"Image (37)\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-37-scaled.jpg\" alt class=\"img-responsive wp-image-16053\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-37-200x113.jpg 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-37-400x225.jpg 400w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-37-600x338.jpg 600w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-37-800x450.jpg 800w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-37-1200x675.jpg 1200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Image-37-scaled.jpg 2560w\" sizes=\"(max-width: 1200px) 100vw, (max-width: 1024px) 100vw, 800px\" \/><\/span><\/div><div class=\"fusion-text fusion-text-5\" style=\"--awb-content-alignment:left;\"><h3>Perspectives d\u2019avenir<\/h3>\n<p>Merci \u00e0 tous les intervenants et participants qui ont contribu\u00e9 \u00e0 une discussion ouverte et engageante, ainsi qu\u2019\u00e0 l\u2019\u00e9quipe de l\u2019Ontario pour avoir organis\u00e9 un \u00e9v\u00e9nement bien men\u00e9 et marquant.<\/p>\n<p>Ground Talk continuera de se d\u00e9velopper.<\/p>\n<p>Nous attendons avec impatience la suite !<\/p>\n<h3>\u00c0 propos de Menard Canada<\/h3>\n<p>Menard Canada (anciennement Geopac) est un entrepreneur sp\u00e9cialis\u00e9 dans la conception-construction g\u00e9otechnique, expert en <a href=\"https:\/\/menardcanada.ca\/fr\/solutions\/\">techniques d\u2019am\u00e9lioration des sols<\/a> pour les conditions de sol difficiles \u00e0 travers le Canada. Fort de plus de 50 ans d\u2019exp\u00e9rience et de 9 bureaux r\u00e9gionaux \u00e0 l\u2019\u00e9chelle nationale, Menard Canada propose des solutions sur mesure pour des projets commerciaux, r\u00e9sidentiels, industriels, institutionnels et d\u2019infrastructure.<\/p>\n<p>Membre du groupe international Menard, l&rsquo;entreprise allie expertise locale et innovation mondiale, r\u00e9alisant plus de 100 <a href=\"https:\/\/menardcanada.ca\/fr\/projets\/\">projets <\/a>par an en tant qu&rsquo;alternative pratique et durable.<\/p>\n<p><a href=\"https:\/\/menardcanada.ca\/fr\/profil\/\">Plus d&rsquo;informations ici<\/a><\/p>\n<p><a href=\"https:\/\/www.linkedin.com\/company\/16215402\">Suivez-nous sur LinkedIn<\/a><\/p>\n<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4524,"featured_media":16027,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[350],"class_list":["post-16021","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","tag-news-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ground Talk Ontario 2026 : une \u00e9tape marquante pour le dialogue de l\u2019industrie!<\/title>\n<meta name=\"description\" content=\"Retour sur Ground Talk Ontario 2026, un \u00e9v\u00e9nement rassemblant des professionnels de l\u2019industrie autour d\u2019\u00e9changes pratiques et de discussions techniques sur les enjeux li\u00e9s au sol.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/menardcanada.ca\/fr\/ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ground Talk Ontario 2026 : une \u00e9tape marquante pour le dialogue de l\u2019industrie!\" \/>\n<meta property=\"og:description\" content=\"Retour sur Ground Talk Ontario 2026, un \u00e9v\u00e9nement rassemblant des professionnels de l\u2019industrie autour d\u2019\u00e9changes pratiques et de discussions techniques sur les enjeux li\u00e9s au sol.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/menardcanada.ca\/fr\/ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets\/\" \/>\n<meta property=\"og:site_name\" content=\"Menard Canada\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-13T04:37:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-16T21:17:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Untitled-design-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"menardcanadainc\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets\\\/\"},\"author\":{\"name\":\"menardcanadainc\",\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/#\\\/schema\\\/person\\\/afc0e94ec2b522f9b3b374a6e82f9a9d\"},\"headline\":\"Ground Talk Ontario 2026 : Une salle comble, des \u00e9changes riches et des enseignements concrets\",\"datePublished\":\"2026-03-13T04:37:23+00:00\",\"dateModified\":\"2026-04-16T21:17:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets\\\/\"},\"wordCount\":1845,\"publisher\":{\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/menardcanada.ca\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2026\\\/04\\\/Untitled-design-1.png\",\"keywords\":[\"News\"],\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets\\\/\",\"url\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets\\\/\",\"name\":\"Ground Talk Ontario 2026 : une \u00e9tape marquante pour le dialogue de l\u2019industrie!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/menardcanada.ca\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2026\\\/04\\\/Untitled-design-1.png\",\"datePublished\":\"2026-03-13T04:37:23+00:00\",\"dateModified\":\"2026-04-16T21:17:55+00:00\",\"description\":\"Retour sur Ground Talk Ontario 2026, un \u00e9v\u00e9nement rassemblant des professionnels de l\u2019industrie autour d\u2019\u00e9changes pratiques et de discussions techniques sur les enjeux li\u00e9s au sol.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets\\\/#primaryimage\",\"url\":\"https:\\\/\\\/menardcanada.ca\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2026\\\/04\\\/Untitled-design-1.png\",\"contentUrl\":\"https:\\\/\\\/menardcanada.ca\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2026\\\/04\\\/Untitled-design-1.png\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualit\u00e9s\",\"item\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/category\\\/actualites\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ground Talk Ontario 2026 : Une salle comble, des \u00e9changes riches et des enseignements concrets\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/\",\"name\":\"Menard Canada\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/#organization\",\"name\":\"Menard group, world specialist in ground improvement\",\"url\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/menardcanada.ca\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2021\\\/06\\\/MENARD-LOGO-icon-above-colour.png\",\"contentUrl\":\"https:\\\/\\\/menardcanada.ca\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2021\\\/06\\\/MENARD-LOGO-icon-above-colour.png\",\"width\":110,\"height\":82,\"caption\":\"Menard group, world specialist in ground improvement\"},\"image\":{\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/menardcanada\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCdvM6StxaNiS1U1g8i7hYEw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/#\\\/schema\\\/person\\\/afc0e94ec2b522f9b3b374a6e82f9a9d\",\"name\":\"menardcanadainc\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61dd2b473bfc2416546fa9216bb5f60f52aab4db9db969e8fba97121a835eafd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61dd2b473bfc2416546fa9216bb5f60f52aab4db9db969e8fba97121a835eafd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61dd2b473bfc2416546fa9216bb5f60f52aab4db9db969e8fba97121a835eafd?s=96&d=mm&r=g\",\"caption\":\"menardcanadainc\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ground Talk Ontario 2026 : une \u00e9tape marquante pour le dialogue de l\u2019industrie!","description":"Retour sur Ground Talk Ontario 2026, un \u00e9v\u00e9nement rassemblant des professionnels de l\u2019industrie autour d\u2019\u00e9changes pratiques et de discussions techniques sur les enjeux li\u00e9s au sol.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/menardcanada.ca\/fr\/ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets\/","og_locale":"fr_FR","og_type":"article","og_title":"Ground Talk Ontario 2026 : une \u00e9tape marquante pour le dialogue de l\u2019industrie!","og_description":"Retour sur Ground Talk Ontario 2026, un \u00e9v\u00e9nement rassemblant des professionnels de l\u2019industrie autour d\u2019\u00e9changes pratiques et de discussions techniques sur les enjeux li\u00e9s au sol.","og_url":"https:\/\/menardcanada.ca\/fr\/ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets\/","og_site_name":"Menard Canada","article_published_time":"2026-03-13T04:37:23+00:00","article_modified_time":"2026-04-16T21:17:55+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Untitled-design-1.png","type":"image\/png"}],"author":"menardcanadainc","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/menardcanada.ca\/fr\/ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets\/#article","isPartOf":{"@id":"https:\/\/menardcanada.ca\/fr\/ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets\/"},"author":{"name":"menardcanadainc","@id":"https:\/\/menardcanada.ca\/fr\/#\/schema\/person\/afc0e94ec2b522f9b3b374a6e82f9a9d"},"headline":"Ground Talk Ontario 2026 : Une salle comble, des \u00e9changes riches et des enseignements concrets","datePublished":"2026-03-13T04:37:23+00:00","dateModified":"2026-04-16T21:17:55+00:00","mainEntityOfPage":{"@id":"https:\/\/menardcanada.ca\/fr\/ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets\/"},"wordCount":1845,"publisher":{"@id":"https:\/\/menardcanada.ca\/fr\/#organization"},"image":{"@id":"https:\/\/menardcanada.ca\/fr\/ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets\/#primaryimage"},"thumbnailUrl":"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Untitled-design-1.png","keywords":["News"],"articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/menardcanada.ca\/fr\/ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets\/","url":"https:\/\/menardcanada.ca\/fr\/ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets\/","name":"Ground Talk Ontario 2026 : une \u00e9tape marquante pour le dialogue de l\u2019industrie!","isPartOf":{"@id":"https:\/\/menardcanada.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/menardcanada.ca\/fr\/ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets\/#primaryimage"},"image":{"@id":"https:\/\/menardcanada.ca\/fr\/ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets\/#primaryimage"},"thumbnailUrl":"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Untitled-design-1.png","datePublished":"2026-03-13T04:37:23+00:00","dateModified":"2026-04-16T21:17:55+00:00","description":"Retour sur Ground Talk Ontario 2026, un \u00e9v\u00e9nement rassemblant des professionnels de l\u2019industrie autour d\u2019\u00e9changes pratiques et de discussions techniques sur les enjeux li\u00e9s au sol.","breadcrumb":{"@id":"https:\/\/menardcanada.ca\/fr\/ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/menardcanada.ca\/fr\/ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/menardcanada.ca\/fr\/ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets\/#primaryimage","url":"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Untitled-design-1.png","contentUrl":"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2026\/04\/Untitled-design-1.png","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/menardcanada.ca\/fr\/ground-talks-ontario-2026-une-salle-comble-des-echanges-riches-et-des-enseignements-concrets\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/menardcanada.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Actualit\u00e9s","item":"https:\/\/menardcanada.ca\/fr\/category\/actualites\/"},{"@type":"ListItem","position":3,"name":"Ground Talk Ontario 2026 : Une salle comble, des \u00e9changes riches et des enseignements concrets"}]},{"@type":"WebSite","@id":"https:\/\/menardcanada.ca\/fr\/#website","url":"https:\/\/menardcanada.ca\/fr\/","name":"Menard Canada","description":"","publisher":{"@id":"https:\/\/menardcanada.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/menardcanada.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/menardcanada.ca\/fr\/#organization","name":"Menard group, world specialist in ground improvement","url":"https:\/\/menardcanada.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/menardcanada.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2021\/06\/MENARD-LOGO-icon-above-colour.png","contentUrl":"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2021\/06\/MENARD-LOGO-icon-above-colour.png","width":110,"height":82,"caption":"Menard group, world specialist in ground improvement"},"image":{"@id":"https:\/\/menardcanada.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/menardcanada","https:\/\/www.youtube.com\/channel\/UCdvM6StxaNiS1U1g8i7hYEw"]},{"@type":"Person","@id":"https:\/\/menardcanada.ca\/fr\/#\/schema\/person\/afc0e94ec2b522f9b3b374a6e82f9a9d","name":"menardcanadainc","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/61dd2b473bfc2416546fa9216bb5f60f52aab4db9db969e8fba97121a835eafd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/61dd2b473bfc2416546fa9216bb5f60f52aab4db9db969e8fba97121a835eafd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/61dd2b473bfc2416546fa9216bb5f60f52aab4db9db969e8fba97121a835eafd?s=96&d=mm&r=g","caption":"menardcanadainc"}}]}},"_links":{"self":[{"href":"https:\/\/menardcanada.ca\/fr\/wp-json\/wp\/v2\/posts\/16021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/menardcanada.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/menardcanada.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/menardcanada.ca\/fr\/wp-json\/wp\/v2\/users\/4524"}],"replies":[{"embeddable":true,"href":"https:\/\/menardcanada.ca\/fr\/wp-json\/wp\/v2\/comments?post=16021"}],"version-history":[{"count":10,"href":"https:\/\/menardcanada.ca\/fr\/wp-json\/wp\/v2\/posts\/16021\/revisions"}],"predecessor-version":[{"id":16104,"href":"https:\/\/menardcanada.ca\/fr\/wp-json\/wp\/v2\/posts\/16021\/revisions\/16104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/menardcanada.ca\/fr\/wp-json\/wp\/v2\/media\/16027"}],"wp:attachment":[{"href":"https:\/\/menardcanada.ca\/fr\/wp-json\/wp\/v2\/media?parent=16021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/menardcanada.ca\/fr\/wp-json\/wp\/v2\/categories?post=16021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/menardcanada.ca\/fr\/wp-json\/wp\/v2\/tags?post=16021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}