{"id":12541,"date":"2023-09-19T20:10:06","date_gmt":"2023-09-19T18:10:06","guid":{"rendered":"https:\/\/menardcanada.ca\/?post_type=avada_portfolio&#038;p=12541"},"modified":"2023-11-16T17:38:59","modified_gmt":"2023-11-16T16:38:59","slug":"entrepot-acericole-plessisville-quebec","status":"publish","type":"avada_portfolio","link":"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/entrepot-acericole-plessisville-quebec\/","title":{"rendered":"Entrep\u00f4t Ac\u00e9ricole: Plessisville, Qu\u00e9bec"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1216.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:3.84%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p style=\"text-align: left;color: #e20025;line-height: 1.32\"><span style=\"color: #e20025\"><span style=\"line-height: 36.96px\" data-fusion-font=\"true\"><span style=\"font-size: 28px\" data-fusion-font=\"true\">Technique s\u00e9lectionn\u00e9e :\u00a0<\/span><br \/>\n<\/span><span style=\"font-size: 28px\"><b>Compactage Dynamique\u00a0<\/b><\/span><\/span><\/p>\n<hr \/>\n<\/div><div class=\"fusion-text fusion-text-2\"><p style=\"text-align: left;color: #e20025;line-height: 1.32\"><span style=\"color: #e20025\"><span style=\"line-height: 36.96px;font-size: 28px\" data-fusion-font=\"true\">Zone de traitement :<br \/>\n<\/span><\/span><b style=\"font-size: 28px\" data-fusion-font=\"true\">13086 m\u00b2<\/b><\/p>\n<hr \/>\n<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-text fusion-text-3\"><p>Menard Canada a \u00e9t\u00e9 mandat\u00e9 par <a href=\"https:\/\/www.pepinfortin.com\/fr\/\" target=\"_blank\" rel=\"noopener noreferrer\">P\u00e9pin Fortin<\/a> pour am\u00e9liorer les sols des fondations du futur entrepot ac\u00e9ricole situ\u00e9 avenue Alphonse Poulin dans le parc industriel de Plessisville (QC).<\/p>\n<h3 class=\"\" data-fontsize=\"20\" data-lineheight=\"28px\">Conditions de sol<\/h3>\n<div class=\"ewa-rteLine\">\n<div class=\"ewa-rteLine\">\n<div class=\"ewa-rteLine\">\n<p>Les donn\u00e9es g\u00e9otechniques extraites des rapports de forage indiquent, dans l\u2019ensemble du site, le profil de sol suivant :<\/p>\n<ul>\n<li>Un couvert v\u00e9g\u00e9tal sur 0.2 m<\/li>\n<li>Un sable gris sur une \u00e9paisseur de 0.8 m<\/li>\n<li>Une couche de SIlt jusqu&rsquo;\u00e0 une profondeur comprise entre 2.44 m et 3.66 m<\/li>\n<li>Un sable gris de compacit\u00e9 moyenne jusqu&rsquo;\u00e0 des profondeurs entre 4.88 m et 7 m<\/li>\n<li>Le Till suivi du Roc au-del\u00e0<\/li>\n<\/ul>\n<\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:3.84%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"1024\" height=\"768\" title=\"Entrepot Acericole_20220524-Grue\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/09\/Entrepot-Acericole_20220524-Grue-1024x768.jpg\" alt class=\"img-responsive wp-image-12714\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/09\/Entrepot-Acericole_20220524-Grue-200x150.jpg 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/09\/Entrepot-Acericole_20220524-Grue-400x300.jpg 400w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/09\/Entrepot-Acericole_20220524-Grue-600x450.jpg 600w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/09\/Entrepot-Acericole_20220524-Grue-800x600.jpg 800w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/09\/Entrepot-Acericole_20220524-Grue-1200x900.jpg 1200w\" sizes=\"(max-width: 1200px) 100vw, (max-width: 1024px) 100vw, 600px\" \/><\/span><\/div><div class=\"fusion-text fusion-text-4\"><p style=\"text-align: center\"><i>Plessisville, Qu\u00e9bec<\/i><\/p>\n<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div style=\"text-align:center;\"><a class=\"fusion-button button-flat button-large button-default fusion-button-default button-1 fusion-button-default-span fusion-button-default-type\" target=\"_self\" href=\"https:\/\/menardcanada.ca\/fr\/contact\/\"><span class=\"fusion-button-icon-divider button-icon-divider-left\"><i class=\"fa-angle-double-right fas awb-button__icon awb-button__icon--default\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-button-text awb-button__text awb-button__text--default fusion-button-text-left\">Contactez-nous d\u00e8s aujourd\u2019hui pour une \u00e9valuation gratuite de votre projet<\/span><\/a><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-5\"><h3 class=\"\" data-fontsize=\"20\" data-lineheight=\"28px\">La solution propos\u00e9e par Menard Canada<\/h3>\n<p>Les criteres de performance etaient d&rsquo;atteindre une capacit\u00e9 portante de 125 kPa pour les fondations et de 50 kPa pour la dalle ainsi que d&rsquo;\u00e9liminer le potentiel de liqu\u00e9faction des sols.<br \/>\nMenard Canada a r\u00e9alis\u00e9 la technique du <a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/compactage-dynamique\/\">Compactage Dynamique<\/a> consistant \u00e0 excaver les sols au droit des fondations et selon une trame sous le dallage, \u00e0 remplacer par du sable MG112 puis \u00e0 venir compacter dynamiquement l&rsquo;ensemble de la superficie. Cette technique est avantageuse car elle limite les volume d&rsquo;excavation \u00e0 r\u00e9aliser. Les forages de controle de type CPT ont permis de valider l&rsquo;obtention des criteres de conception.<\/p>\n<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1216.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-section-separator section-separator triangle fusion-section-separator-1\" style=\"--awb-border-top:1px solid #f6f6f6;--awb-spacer-height:1px;--awb-svg-margin-left:1.92%;--awb-svg-margin-right:1.92%;--awb-svg-margin-left-medium:1.92%;--awb-svg-margin-right-medium:1.92%;--awb-svg-margin-left-small:1.92%;--awb-svg-margin-right-small:1.92%;--awb-icon-color:;\"><div class=\"fusion-section-separator-svg\"><div class=\"divider-candy-arrow top\" style=\"bottom:0px;border-bottom-color: #f6f6f6;\"><\/div><div class=\"divider-candy top\" style=\"top:-21px;border-bottom:1px solid #f6f6f6;border-left:1px solid #f6f6f6;\"><\/div><\/div><div class=\"fusion-section-separator-spacer\"><div class=\"fusion-section-separator-spacer-height\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:20px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-6\"><h2 class=\"\" style=\"line-height: 1.4\" data-fontsize=\"20\" data-lineheight=\"28px\">Explore Other Projects<\/h2>\n<\/div><div class=\"fusion-recent-works fusion-portfolio-element fusion-portfolio fusion-portfolio-1 fusion-portfolio-carousel fusion-portfolio-paging-infinite recent-works-carousel portfolio-carousel picture-size-auto fusion-portfolio-rollover\" data-id=\"-rw-1\"><div class=\"awb-carousel awb-swiper awb-swiper-carousel fusion-carousel-title-below-image\" style=\"--awb-columns:3;\" data-metacontent=\"yes\" data-autoplay=\"no\" data-columns=\"3\" data-itemmargin=\"30\" data-itemwidth=\"180\" data-touchscroll=\"no\" data-imagesize=\"auto\"><div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Complexe r\u00e9cr\u00e9atif de Russell \u2013 Phase 1 et 2, Ontario<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/jenniferlemarec\/\" rel=\"author\">jenniferlemarec<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2025-09-10T20:32:35+02:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"2048\" height=\"1536\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2024\/09\/Sportsplex-ON-2023.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2024\/09\/Sportsplex-ON-2023-200x150.jpg 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2024\/09\/Sportsplex-ON-2023-400x300.jpg 400w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2024\/09\/Sportsplex-ON-2023-600x450.jpg 600w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2024\/09\/Sportsplex-ON-2023-800x600.jpg 800w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2024\/09\/Sportsplex-ON-2023-1200x900.jpg 1200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2024\/09\/Sportsplex-ON-2023.jpg 2048w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/complexe-recreatif-de-russell-phase-1-ontario\/\">Complexe r\u00e9cr\u00e9atif de Russell \u2013 Phase 1 et 2, Ontario<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/complexe-recreatif-de-russell-phase-1-ontario\/\" aria-label=\"Complexe r\u00e9cr\u00e9atif de Russell \u2013 Phase 1 et 2, Ontario\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/complexe-recreatif-de-russell-phase-1-ontario\/\" target=\"_self\">Complexe r\u00e9cr\u00e9atif de Russell \u2013 Phase 1 et 2, Ontario<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/batiments\/\" rel=\"tag\">B\u00e2timents<\/a>, <a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/colonnes-a-module-controle-cmc\/\" rel=\"tag\">Colonnes \u00e0 Module Contr\u00f4l\u00e9 (CMC)<\/a>, <a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/consolidification-fr\/\" rel=\"tag\">Consolidification<\/a>, <a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/drains-verticaux\/\" rel=\"tag\">Drains Verticaux<\/a>, <a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Entrep\u00f4t : Vars, Ontario<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/jenniferlemarec\/\" rel=\"author\">jenniferlemarec<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2025-09-16T21:29:47+02:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"2048\" height=\"1536\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2024\/09\/CMC-Vars-industrial-Warehouse-2023.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2024\/09\/CMC-Vars-industrial-Warehouse-2023-200x150.jpg 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2024\/09\/CMC-Vars-industrial-Warehouse-2023-400x300.jpg 400w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2024\/09\/CMC-Vars-industrial-Warehouse-2023-600x450.jpg 600w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2024\/09\/CMC-Vars-industrial-Warehouse-2023-800x600.jpg 800w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2024\/09\/CMC-Vars-industrial-Warehouse-2023-1200x900.jpg 1200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2024\/09\/CMC-Vars-industrial-Warehouse-2023.jpg 2048w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/warehouse-vars-ontario\/\">Entrep\u00f4t : Vars, Ontario<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/warehouse-vars-ontario\/\" aria-label=\"Entrep\u00f4t : Vars, Ontario\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/warehouse-vars-ontario\/\" target=\"_self\">Entrep\u00f4t : Vars, Ontario<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/batiments\/\" rel=\"tag\">B\u00e2timents<\/a>, <a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/colonnes-a-module-controle-cmc\/\" rel=\"tag\">Colonnes \u00e0 Module Contr\u00f4l\u00e9 (CMC)<\/a>, <a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a>, <a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/renforcement\/\" rel=\"tag\">Renforcement<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">R\u00e9sidence \u00e9tudiante, Universit\u00e9 McMaster : Hamilton, Ontario<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/benzion\/\" rel=\"author\">Menard Canada<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2024-09-06T23:20:48+02:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2024\/07\/Mc-Master-ON-CMC-2024-21-scaled.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2024\/07\/Mc-Master-ON-CMC-2024-21-200x150.jpg 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2024\/07\/Mc-Master-ON-CMC-2024-21-400x300.jpg 400w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2024\/07\/Mc-Master-ON-CMC-2024-21-600x450.jpg 600w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2024\/07\/Mc-Master-ON-CMC-2024-21-800x600.jpg 800w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2024\/07\/Mc-Master-ON-CMC-2024-21-1200x900.jpg 1200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2024\/07\/Mc-Master-ON-CMC-2024-21-scaled.jpg 2560w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/residence-etudiante-universite-mcmaster-hamilton-ontario\/\">R\u00e9sidence \u00e9tudiante, Universit\u00e9 McMaster : Hamilton, Ontario<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/residence-etudiante-universite-mcmaster-hamilton-ontario\/\" aria-label=\"R\u00e9sidence \u00e9tudiante, Universit\u00e9 McMaster : Hamilton, Ontario\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/residence-etudiante-universite-mcmaster-hamilton-ontario\/\" target=\"_self\">R\u00e9sidence \u00e9tudiante, Universit\u00e9 McMaster : Hamilton, Ontario<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/batiments\/\" rel=\"tag\">B\u00e2timents<\/a>, <a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/colonnes-a-module-controle-cmc\/\" rel=\"tag\">Colonnes \u00e0 Module Contr\u00f4l\u00e9 (CMC)<\/a>, <a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a>, <a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/renforcement\/\" rel=\"tag\">Renforcement<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Centre de distribution Metro: Terrebonne, Qu\u00e9bec<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/menardcanadainc\/\" rel=\"author\">menardcanadainc<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-15T21:00:24+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"2016\" height=\"1512\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/11\/MicrosoftTeams-image-174.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Centre de distribution Metro Terrebonne\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/11\/MicrosoftTeams-image-174-200x150.jpg 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/11\/MicrosoftTeams-image-174-400x300.jpg 400w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/11\/MicrosoftTeams-image-174-600x450.jpg 600w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/11\/MicrosoftTeams-image-174-800x600.jpg 800w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/11\/MicrosoftTeams-image-174-1200x900.jpg 1200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/11\/MicrosoftTeams-image-174.jpg 2016w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/centre-de-distribution-metro-terrebonne-quebec\/\">Centre de distribution Metro: Terrebonne, Qu\u00e9bec<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/centre-de-distribution-metro-terrebonne-quebec\/\" aria-label=\"Centre de distribution Metro: Terrebonne, Qu\u00e9bec\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/centre-de-distribution-metro-terrebonne-quebec\/\" target=\"_self\">Centre de distribution Metro: Terrebonne, Qu\u00e9bec<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Entrep\u00f4t Ac\u00e9ricole: Plessisville, Qu\u00e9bec<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/benzion\/\" rel=\"author\">Menard Canada<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-16T17:38:59+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/09\/Entrepot-Acericole_20220524-Grue-scaled.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/09\/Entrepot-Acericole_20220524-Grue-200x150.jpg 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/09\/Entrepot-Acericole_20220524-Grue-400x300.jpg 400w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/09\/Entrepot-Acericole_20220524-Grue-600x450.jpg 600w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/09\/Entrepot-Acericole_20220524-Grue-800x600.jpg 800w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/09\/Entrepot-Acericole_20220524-Grue-1200x900.jpg 1200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/09\/Entrepot-Acericole_20220524-Grue-scaled.jpg 2560w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/entrepot-acericole-plessisville-quebec\/\">Entrep\u00f4t Ac\u00e9ricole: Plessisville, Qu\u00e9bec<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/entrepot-acericole-plessisville-quebec\/\" aria-label=\"Entrep\u00f4t Ac\u00e9ricole: Plessisville, Qu\u00e9bec\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/entrepot-acericole-plessisville-quebec\/\" target=\"_self\">Entrep\u00f4t Ac\u00e9ricole: Plessisville, Qu\u00e9bec<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">B\u00e2timent multiusage : Laval, Qu\u00e9bec<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/benzion\/\" rel=\"author\">Menard Canada<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-09-19T20:06:31+02:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-5.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-5-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-5.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/batiment-multiusage-laval-quebec\/\">B\u00e2timent multiusage : Laval, Qu\u00e9bec<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/batiment-multiusage-laval-quebec\/\" aria-label=\"B\u00e2timent multiusage : Laval, Qu\u00e9bec\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/batiment-multiusage-laval-quebec\/\" target=\"_self\">B\u00e2timent multiusage : Laval, Qu\u00e9bec<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">B\u00e2timent industriel Rosefellow : Qu\u00e9bec<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/benzion\/\" rel=\"author\">Menard Canada<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-09-19T20:04:34+02:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-17.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-17-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-17.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/batiment-industriel-rosefellow-quebec\/\">B\u00e2timent industriel Rosefellow : Qu\u00e9bec<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/batiment-industriel-rosefellow-quebec\/\" aria-label=\"B\u00e2timent industriel Rosefellow : Qu\u00e9bec\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/batiment-industriel-rosefellow-quebec\/\" target=\"_self\">B\u00e2timent industriel Rosefellow : Qu\u00e9bec<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Multi-r\u00e9sidentiel: Saint-Charles-Borrom\u00e9e, Qu\u00e9bec<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/benzion\/\" rel=\"author\">Menard Canada<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-16T16:22:27+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-13.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-13-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-13.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/multi-residentiel-saint-charles-borromee-quebec\/\">Multi-r\u00e9sidentiel: Saint-Charles-Borrom\u00e9e, Qu\u00e9bec<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/multi-residentiel-saint-charles-borromee-quebec\/\" aria-label=\"Multi-r\u00e9sidentiel: Saint-Charles-Borrom\u00e9e, Qu\u00e9bec\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/multi-residentiel-saint-charles-borromee-quebec\/\" target=\"_self\">Multi-r\u00e9sidentiel: Saint-Charles-Borrom\u00e9e, Qu\u00e9bec<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">B\u00e2timent multi-r\u00e9sidentiel : R\u00e9pentigny, Qu\u00e9bec<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/benzion\/\" rel=\"author\">Menard Canada<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-09-19T22:26:00+02:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-11.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-11-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-11.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/batiment-multi-residentiel-repentigny-quebec\/\">B\u00e2timent multi-r\u00e9sidentiel : R\u00e9pentigny, Qu\u00e9bec<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/batiment-multi-residentiel-repentigny-quebec\/\" aria-label=\"B\u00e2timent multi-r\u00e9sidentiel : R\u00e9pentigny, Qu\u00e9bec\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/batiment-multi-residentiel-repentigny-quebec\/\" target=\"_self\">B\u00e2timent multi-r\u00e9sidentiel : R\u00e9pentigny, Qu\u00e9bec<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">B\u00e2timent industriel Rosefellow : Beauharnois, Qu\u00e9bec<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/benzion\/\" rel=\"author\">Menard Canada<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-10-24T21:28:05+02:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Sans-titre-14.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Sans-titre-14-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Sans-titre-14.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/batiment-industriel-rosefellow-beauharnois-quebec\/\">B\u00e2timent industriel Rosefellow : Beauharnois, Qu\u00e9bec<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/batiment-industriel-rosefellow-beauharnois-quebec\/\" aria-label=\"B\u00e2timent industriel Rosefellow : Beauharnois, Qu\u00e9bec\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/batiment-industriel-rosefellow-beauharnois-quebec\/\" target=\"_self\">B\u00e2timent industriel Rosefellow : Beauharnois, Qu\u00e9bec<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Entrep\u00f4t : Val d\u2019Or, Qu\u00e9bec<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/benzion\/\" rel=\"author\">Menard Canada<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-16T17:48:45+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-29.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-29-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-29.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/manufacturing-facility-val-dor-quebec\/\">Entrep\u00f4t : Val d\u2019Or, Qu\u00e9bec<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/manufacturing-facility-val-dor-quebec\/\" aria-label=\"Entrep\u00f4t : Val d\u2019Or, Qu\u00e9bec\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/manufacturing-facility-val-dor-quebec\/\" target=\"_self\">Entrep\u00f4t : Val d\u2019Or, Qu\u00e9bec<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Entrep\u00f4t et Bureaux Fruit d&rsquo;Or: Plessisville, Qu\u00e9bec<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/benzion\/\" rel=\"author\">Menard Canada<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-16T17:30:03+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-18.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-18-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-18.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/entrepot-et-bureaux-fruit-dor-plessisville-quebec\/\">Entrep\u00f4t et Bureaux Fruit d&rsquo;Or: Plessisville, Qu\u00e9bec<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/entrepot-et-bureaux-fruit-dor-plessisville-quebec\/\" aria-label=\"Entrep\u00f4t et Bureaux Fruit d&rsquo;Or: Plessisville, Qu\u00e9bec\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/entrepot-et-bureaux-fruit-dor-plessisville-quebec\/\" target=\"_self\">Entrep\u00f4t et Bureaux Fruit d&rsquo;Or: Plessisville, Qu\u00e9bec<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">R\u00e9sidence Sainte-Anne-des-Monts, Qu\u00e9bec<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/benzion\/\" rel=\"author\">Menard Canada<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-15T21:37:29+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-25.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-25-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-25.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/residence-sainte-anne-des-monts-quebec\/\">R\u00e9sidence Sainte-Anne-des-Monts, Qu\u00e9bec<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/residence-sainte-anne-des-monts-quebec\/\" aria-label=\"R\u00e9sidence Sainte-Anne-des-Monts, Qu\u00e9bec\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/residence-sainte-anne-des-monts-quebec\/\" target=\"_self\">R\u00e9sidence Sainte-Anne-des-Monts, Qu\u00e9bec<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Tour de T\u00e9l\u00e9communication Videotron: Rigaud, Qu\u00e9bec<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/benzion\/\" rel=\"author\">Menard Canada<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-15T20:57:02+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-27.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-27-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-27.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/tour-telecommunication-videotron-rigaud-quebec\/\">Tour de T\u00e9l\u00e9communication Videotron: Rigaud, Qu\u00e9bec<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/tour-telecommunication-videotron-rigaud-quebec\/\" aria-label=\"Tour de T\u00e9l\u00e9communication Videotron: Rigaud, Qu\u00e9bec\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/tour-telecommunication-videotron-rigaud-quebec\/\" target=\"_self\">Tour de T\u00e9l\u00e9communication Videotron: Rigaud, Qu\u00e9bec<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">\u00c9difice F\u00e9d\u00e9ral: Shawinigan, Qu\u00e9bec<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/benzion\/\" rel=\"author\">Menard Canada<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-16T18:15:15+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/09\/Edifice-Federal_image00001-1200x900-1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/09\/Edifice-Federal_image00001-1200x900-1-200x150.jpg 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/09\/Edifice-Federal_image00001-1200x900-1.jpg 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/edifice-federal-shawinigan-quebec\/\">\u00c9difice F\u00e9d\u00e9ral: Shawinigan, Qu\u00e9bec<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/edifice-federal-shawinigan-quebec\/\" aria-label=\"\u00c9difice F\u00e9d\u00e9ral: Shawinigan, Qu\u00e9bec\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/edifice-federal-shawinigan-quebec\/\" target=\"_self\">\u00c9difice F\u00e9d\u00e9ral: Shawinigan, Qu\u00e9bec<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Usine Innomalt: B\u00e9cancour, Qu\u00e9bec<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/benzion\/\" rel=\"author\">Menard Canada<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-15T20:49:46+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-19.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-19-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-19.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/usine-innomalt-becancour-quebec\/\">Usine Innomalt: B\u00e9cancour, Qu\u00e9bec<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/usine-innomalt-becancour-quebec\/\" aria-label=\"Usine Innomalt: B\u00e9cancour, Qu\u00e9bec\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/usine-innomalt-becancour-quebec\/\" target=\"_self\">Usine Innomalt: B\u00e9cancour, Qu\u00e9bec<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Entrep\u00f4t CANAC : Saint-Nicolas, Qu\u00e9bec<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/benzion\/\" rel=\"author\">Menard Canada<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-16T17:33:31+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-16.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-16-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-16.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/entrepot-canac-saint-nicolas-quebec\/\">Entrep\u00f4t CANAC : Saint-Nicolas, Qu\u00e9bec<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/entrepot-canac-saint-nicolas-quebec\/\" aria-label=\"Entrep\u00f4t CANAC : Saint-Nicolas, Qu\u00e9bec\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/entrepot-canac-saint-nicolas-quebec\/\" target=\"_self\">Entrep\u00f4t CANAC : Saint-Nicolas, Qu\u00e9bec<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">B\u00e2timents commerciaux : Pont Rouge, Qu\u00e9bec<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/benzion\/\" rel=\"author\">Menard Canada<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-09-19T19:38:09+02:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-3.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-3-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-3.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/batiments-commerciaux-pont-rouge-quebec\/\">B\u00e2timents commerciaux : Pont Rouge, Qu\u00e9bec<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/batiments-commerciaux-pont-rouge-quebec\/\" aria-label=\"B\u00e2timents commerciaux : Pont Rouge, Qu\u00e9bec\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/batiments-commerciaux-pont-rouge-quebec\/\" target=\"_self\">B\u00e2timents commerciaux : Pont Rouge, Qu\u00e9bec<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Logement r\u00e9sidentiel : Trois-Rivi\u00e8res, Qu\u00e9bec<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/benzion\/\" rel=\"author\">Menard Canada<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-16T17:04:31+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-15.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-15-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/06\/Green-Modern-Professional-Service-Email-Header-300-\u00d7-225-px-15.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/logement-residentiel-trois-rivieres-quebec\/\">Logement r\u00e9sidentiel : Trois-Rivi\u00e8res, Qu\u00e9bec<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/logement-residentiel-trois-rivieres-quebec\/\" aria-label=\"Logement r\u00e9sidentiel : Trois-Rivi\u00e8res, Qu\u00e9bec\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/logement-residentiel-trois-rivieres-quebec\/\" target=\"_self\">Logement r\u00e9sidentiel : Trois-Rivi\u00e8res, Qu\u00e9bec<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Oceanfront Park Phase A: Squamish, British Columbia<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/menardcanadainc\/\" rel=\"author\">menardcanadainc<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-16T16:21:11+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/01\/Untitled-design-1.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/01\/Untitled-design-1-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/01\/Untitled-design-1.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/oceanfront-park-squamish-british-columbia\/\">Oceanfront Park Phase A: Squamish, British Columbia<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/oceanfront-park-squamish-british-columbia\/\" aria-label=\"Oceanfront Park Phase A: Squamish, British Columbia\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/oceanfront-park-squamish-british-columbia\/\" target=\"_self\">Oceanfront Park Phase A: Squamish, British Columbia<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Station de traitement des eaux us\u00e9es : Vancouver, Colombie-Britannique<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/menardcanadainc\/\" rel=\"author\">menardcanadainc<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-23T10:54:41+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Untitled-design-1.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Untitled-design-1-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Untitled-design-1.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/station-traitement-eaux-usees-vancouver-colombie-britannique\/\">Station de traitement des eaux us\u00e9es : Vancouver, Colombie-Britannique<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/station-traitement-eaux-usees-vancouver-colombie-britannique\/\" aria-label=\"Station de traitement des eaux us\u00e9es : Vancouver, Colombie-Britannique\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/station-traitement-eaux-usees-vancouver-colombie-britannique\/\" target=\"_self\">Station de traitement des eaux us\u00e9es : Vancouver, Colombie-Britannique<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">B\u00e2timent Industriel : Brantford, Ontario<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/coralielaval\/\" rel=\"author\">coralielaval<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-05-02T23:09:47+02:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/admin-ajax-2-1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/admin-ajax-2-1-200x150.jpg 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/admin-ajax-2-1.jpg 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/batiment-industriel-brantford-ontario\/\">B\u00e2timent Industriel : Brantford, Ontario<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/batiment-industriel-brantford-ontario\/\" aria-label=\"B\u00e2timent Industriel : Brantford, Ontario\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/batiment-industriel-brantford-ontario\/\" target=\"_self\">B\u00e2timent Industriel : Brantford, Ontario<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Docks de Fraser Surrey : Surrey, Colombie-Britannique<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/coralielaval\/\" rel=\"author\">coralielaval<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2024-05-20T21:51:13+02:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"382\" height=\"287\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/admin-ajax-1-e1663167406195.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/docks-de-fraser-surrey-surrey-colombie-britannique\/\">Docks de Fraser Surrey : Surrey, Colombie-Britannique<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/docks-de-fraser-surrey-surrey-colombie-britannique\/\" aria-label=\"Docks de Fraser Surrey : Surrey, Colombie-Britannique\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/docks-de-fraser-surrey-surrey-colombie-britannique\/\" target=\"_self\">Docks de Fraser Surrey : Surrey, Colombie-Britannique<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Exploitation mini\u00e8re &#8211; Lac Rouge, Ontario<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/coralielaval\/\" rel=\"author\">coralielaval<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-16T17:15:53+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/10-scaled-1-e1663165993800.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/exploitation-miniere-lac-rouge-ontario\/\">Exploitation mini\u00e8re &#8211; Lac Rouge, Ontario<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/exploitation-miniere-lac-rouge-ontario\/\" aria-label=\"Exploitation mini\u00e8re &#8211; Lac Rouge, Ontario\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/exploitation-miniere-lac-rouge-ontario\/\" target=\"_self\">Exploitation mini\u00e8re &#8211; Lac Rouge, Ontario<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Centre des Op\u00e9rations Hydro One : Dunnville, Ontario<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/coralielaval\/\" rel=\"author\">coralielaval<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-05-02T23:06:41+02:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/11-EDITED-scaled-1-e1663165510404.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/centre-des-operations-hydro-one-dunnville-ontario\/\">Centre des Op\u00e9rations Hydro One : Dunnville, Ontario<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/centre-des-operations-hydro-one-dunnville-ontario\/\" aria-label=\"Centre des Op\u00e9rations Hydro One : Dunnville, Ontario\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/centre-des-operations-hydro-one-dunnville-ontario\/\" target=\"_self\">Centre des Op\u00e9rations Hydro One : Dunnville, Ontario<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Poste de Minette : Kitimat, Colombie-Britannique<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/coralielaval\/\" rel=\"author\">coralielaval<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-15T21:49:40+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/12-EDITED-scaled-1-e1663165328236.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/poste-de-minette-kitimat-colombie-britannique\/\">Poste de Minette : Kitimat, Colombie-Britannique<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/poste-de-minette-kitimat-colombie-britannique\/\" aria-label=\"Poste de Minette : Kitimat, Colombie-Britannique\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/poste-de-minette-kitimat-colombie-britannique\/\" target=\"_self\">Poste de Minette : Kitimat, Colombie-Britannique<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">R\u00e9sidence \u00c9tudiante : Universit\u00e9 de Toronto, Ontario<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/coralielaval\/\" rel=\"author\">coralielaval<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-15T21:24:39+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/300x225-pixels-Website-1.png\" class=\"attachment-full size-full wp-post-image\" alt=\"University of Toronto Scarborough Student Residence - Toronto (ON)\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/300x225-pixels-Website-1-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/300x225-pixels-Website-1.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/residence-etudiante-universite-de-toronto-ontario\/\">R\u00e9sidence \u00c9tudiante : Universit\u00e9 de Toronto, Ontario<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/residence-etudiante-universite-de-toronto-ontario\/\" aria-label=\"R\u00e9sidence \u00c9tudiante : Universit\u00e9 de Toronto, Ontario\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/residence-etudiante-universite-de-toronto-ontario\/\" target=\"_self\">R\u00e9sidence \u00c9tudiante : Universit\u00e9 de Toronto, Ontario<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Am\u00e9lioration des digues : Delta, Colombie-Britannique<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/coralielaval\/\" rel=\"author\">coralielaval<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-05-17T22:55:44+02:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/13-1-EDITED-scaled_300x225.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/13-1-EDITED-scaled_300x225-200x150.jpeg 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/13-1-EDITED-scaled_300x225.jpeg 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/amelioration-des-digues-delta-colombie-britannique\/\">Am\u00e9lioration des digues : Delta, Colombie-Britannique<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/amelioration-des-digues-delta-colombie-britannique\/\" aria-label=\"Am\u00e9lioration des digues : Delta, Colombie-Britannique\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/amelioration-des-digues-delta-colombie-britannique\/\" target=\"_self\">Am\u00e9lioration des digues : Delta, Colombie-Britannique<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Entrep\u00f4t : Sorel-Tracy, Qu\u00e9bec<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/coralielaval\/\" rel=\"author\">coralielaval<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-16T18:10:28+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Sans-titre-10.png\" class=\"attachment-full size-full wp-post-image\" alt=\"Multifunctional Warehouse - Marine Terminal, Sorel-Tracy, Qu\u00e9bec\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Sans-titre-10-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Sans-titre-10.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/entrepot-sorel-tracy-quebec\/\">Entrep\u00f4t : Sorel-Tracy, Qu\u00e9bec<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/entrepot-sorel-tracy-quebec\/\" aria-label=\"Entrep\u00f4t : Sorel-Tracy, Qu\u00e9bec\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/entrepot-sorel-tracy-quebec\/\" target=\"_self\">Entrep\u00f4t : Sorel-Tracy, Qu\u00e9bec<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">\u00c9oliennes Val-\u00c9O : St-G\u00e9d\u00e9on, Qu\u00e9bec<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/coralielaval\/\" rel=\"author\">coralielaval<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-16T17:19:39+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/14-2-EDITED-1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/14-2-EDITED-1-200x150.jpg 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/14-2-EDITED-1.jpg 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/eoliennes-val-eo-st-gedeon-quebec\/\">\u00c9oliennes Val-\u00c9O : St-G\u00e9d\u00e9on, Qu\u00e9bec<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/eoliennes-val-eo-st-gedeon-quebec\/\" aria-label=\"\u00c9oliennes Val-\u00c9O : St-G\u00e9d\u00e9on, Qu\u00e9bec\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/eoliennes-val-eo-st-gedeon-quebec\/\" target=\"_self\">\u00c9oliennes Val-\u00c9O : St-G\u00e9d\u00e9on, Qu\u00e9bec<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">\u00c9cole : Hamilton, Ontario<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/coralielaval\/\" rel=\"author\">coralielaval<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-05-02T22:55:37+02:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Sans-titre-11.png\" class=\"attachment-full size-full wp-post-image\" alt=\"School Building, St. Patricks Catholic Elementary School, Hamilton Ontario\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Sans-titre-11-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Sans-titre-11.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/ecole-hamilton-ontario\/\">\u00c9cole : Hamilton, Ontario<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/ecole-hamilton-ontario\/\" aria-label=\"\u00c9cole : Hamilton, Ontario\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/ecole-hamilton-ontario\/\" target=\"_self\">\u00c9cole : Hamilton, Ontario<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Maison des A\u00een\u00e9s : Alma, Qu\u00e9bec<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/coralielaval\/\" rel=\"author\">coralielaval<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-16T16:54:33+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/300x225-pixels-Website-5.png\" class=\"attachment-full size-full wp-post-image\" alt=\"Maison des A\u00een\u00e9s, Alma, Qu\u00e9bec\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/300x225-pixels-Website-5-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/300x225-pixels-Website-5.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/maison-des-aines-alma-quebec\/\">Maison des A\u00een\u00e9s : Alma, Qu\u00e9bec<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/maison-des-aines-alma-quebec\/\" aria-label=\"Maison des A\u00een\u00e9s : Alma, Qu\u00e9bec\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/maison-des-aines-alma-quebec\/\" target=\"_self\">Maison des A\u00een\u00e9s : Alma, Qu\u00e9bec<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Installation de Deltaport : Delta Colombie-britannique<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/coralielaval\/\" rel=\"author\">coralielaval<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-16T17:09:54+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Sans-titre-13.png\" class=\"attachment-full size-full wp-post-image\" alt=\"Deltaport Truck Staging Facility, Delta British Colombia\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Sans-titre-13-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Sans-titre-13.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/installation-de-deltaport-delta-colombie-britannique\/\">Installation de Deltaport : Delta Colombie-britannique<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/installation-de-deltaport-delta-colombie-britannique\/\" aria-label=\"Installation de Deltaport : Delta Colombie-britannique\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/installation-de-deltaport-delta-colombie-britannique\/\" target=\"_self\">Installation de Deltaport : Delta Colombie-britannique<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Am\u00e9lioration route 389 : Baie Comeau, Qu\u00e9bec<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/coralielaval\/\" rel=\"author\">coralielaval<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2024-09-04T04:02:26+02:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Sans-titre-14.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Sans-titre-14-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Sans-titre-14.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/amelioration-route-389-baie-comeau-quebec\/\">Am\u00e9lioration route 389 : Baie Comeau, Qu\u00e9bec<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/amelioration-route-389-baie-comeau-quebec\/\" aria-label=\"Am\u00e9lioration route 389 : Baie Comeau, Qu\u00e9bec\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/amelioration-route-389-baie-comeau-quebec\/\" target=\"_self\">Am\u00e9lioration route 389 : Baie Comeau, Qu\u00e9bec<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">P\u00e9riph\u00e9rique de l&rsquo;Ouest de Calgary, Alberta<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/coralielaval\/\" rel=\"author\">coralielaval<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-16T16:15:23+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Untitled-design-1-1.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Untitled-design-1-1-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Untitled-design-1-1.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/peripherique-de-louest-de-calgary-alberta\/\">P\u00e9riph\u00e9rique de l&rsquo;Ouest de Calgary, Alberta<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/peripherique-de-louest-de-calgary-alberta\/\" aria-label=\"P\u00e9riph\u00e9rique de l&rsquo;Ouest de Calgary, Alberta\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/peripherique-de-louest-de-calgary-alberta\/\" target=\"_self\">P\u00e9riph\u00e9rique de l&rsquo;Ouest de Calgary, Alberta<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Autoroute 91-17 : Delta, Colombie-Britannique<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/coralielaval\/\" rel=\"author\">coralielaval<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-05-02T22:48:37+02:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Sans-titre-17.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Sans-titre-17-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Sans-titre-17.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/autoroute-91-17-delta-colombie-britannique\/\">Autoroute 91-17 : Delta, Colombie-Britannique<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/autoroute-91-17-delta-colombie-britannique\/\" aria-label=\"Autoroute 91-17 : Delta, Colombie-Britannique\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/autoroute-91-17-delta-colombie-britannique\/\" target=\"_self\">Autoroute 91-17 : Delta, Colombie-Britannique<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Chemin de fer Coquitlam: Colombie-Britannique<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/coralielaval\/\" rel=\"author\">coralielaval<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-05-02T22:47:20+02:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/300x225-pixels-Website-6.png\" class=\"attachment-full size-full wp-post-image\" alt=\"Canadian Pacific Rail, Coquitlam, British Columbia\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/300x225-pixels-Website-6-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/300x225-pixels-Website-6.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/chemin-de-fer-coquitlam-colombie-britannique\/\">Chemin de fer Coquitlam: Colombie-Britannique<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/chemin-de-fer-coquitlam-colombie-britannique\/\" aria-label=\"Chemin de fer Coquitlam: Colombie-Britannique\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/chemin-de-fer-coquitlam-colombie-britannique\/\" target=\"_self\">Chemin de fer Coquitlam: Colombie-Britannique<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Entrep\u00f4t: Calgary, Alberta<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/menardcanadainc\/\" rel=\"author\">menardcanadainc<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-16T17:25:31+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/300x225-pixels-Website.png\" class=\"attachment-full size-full wp-post-image\" alt=\"YYC4 Project Maverick - Warehouse - Calgary (AB)\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/300x225-pixels-Website-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/300x225-pixels-Website.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/entrepot-calgary-alberta\/\">Entrep\u00f4t: Calgary, Alberta<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/entrepot-calgary-alberta\/\" aria-label=\"Entrep\u00f4t: Calgary, Alberta\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/entrepot-calgary-alberta\/\" target=\"_self\">Entrep\u00f4t: Calgary, Alberta<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">D\u00e9veloppement R\u00e9sidentiel : Toronto, Ontario<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/menardcanadainc\/\" rel=\"author\">menardcanadainc<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-05-02T22:44:38+02:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/300x225-pixels-Website-4.png\" class=\"attachment-full size-full wp-post-image\" alt=\"Residential Development \u2013 Keele Street, Toronto, Ontario\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/300x225-pixels-Website-4-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/300x225-pixels-Website-4.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/developpement-residentiel-toronto\/\">D\u00e9veloppement R\u00e9sidentiel : Toronto, Ontario<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/developpement-residentiel-toronto\/\" aria-label=\"D\u00e9veloppement R\u00e9sidentiel : Toronto, Ontario\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/developpement-residentiel-toronto\/\" target=\"_self\">D\u00e9veloppement R\u00e9sidentiel : Toronto, Ontario<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Barrage n\u00b0 5 : \u00eele de Vancouver, Colombie-Britannique<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/benzion\/\" rel=\"author\">Menard Canada<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-10-09T22:31:30+02:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"1436\" height=\"1077\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/8-EDITED-e1663167461442.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/butchart-dam-no-5\/\">Barrage n\u00b0 5 : \u00eele de Vancouver, Colombie-Britannique<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/butchart-dam-no-5\/\" aria-label=\"Barrage n\u00b0 5 : \u00eele de Vancouver, Colombie-Britannique\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/butchart-dam-no-5\/\" target=\"_self\">Barrage n\u00b0 5 : \u00eele de Vancouver, Colombie-Britannique<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Am\u00e9lioration de la digue : New Westminster, Colombie Britannique<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/benzion\/\" rel=\"author\">Menard Canada<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-10-09T22:26:47+02:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/7-EDITED-scaled-1-e1663167513802.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/digue-new-westminster\/\">Am\u00e9lioration de la digue : New Westminster, Colombie Britannique<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/digue-new-westminster\/\" aria-label=\"Am\u00e9lioration de la digue : New Westminster, Colombie Britannique\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/digue-new-westminster\/\" target=\"_self\">Am\u00e9lioration de la digue : New Westminster, Colombie Britannique<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Construction d&rsquo;un H\u00f4tel : Thunder Bay, Ontario<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/menardcanadainc\/\" rel=\"author\">menardcanadainc<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-05-02T22:38:14+02:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/300x225-pixels-Website-3.png\" class=\"attachment-full size-full wp-post-image\" alt=\"Hotel Development, Thunder Bay (ON)\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/300x225-pixels-Website-3-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/300x225-pixels-Website-3.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/hotel-development-thunder-bay-ontario\/\">Construction d&rsquo;un H\u00f4tel : Thunder Bay, Ontario<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/hotel-development-thunder-bay-ontario\/\" aria-label=\"Construction d&rsquo;un H\u00f4tel : Thunder Bay, Ontario\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/hotel-development-thunder-bay-ontario\/\" target=\"_self\">Construction d&rsquo;un H\u00f4tel : Thunder Bay, Ontario<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Modernisation d&rsquo;une station de pompage: Vancouver, Colombie-Britannique<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/benzion\/\" rel=\"author\">Menard Canada<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-16T16:25:06+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/5-1-EDITED-scaled-1-e1663167617877.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/modernisation-station-pompage-vancouver\/\">Modernisation d&rsquo;une station de pompage: Vancouver, Colombie-Britannique<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/modernisation-station-pompage-vancouver\/\" aria-label=\"Modernisation d&rsquo;une station de pompage: Vancouver, Colombie-Britannique\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/modernisation-station-pompage-vancouver\/\" target=\"_self\">Modernisation d&rsquo;une station de pompage: Vancouver, Colombie-Britannique<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Lotissement R\u00e9sidentiel: Whitby, Ontario<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/menardcanadainc\/\" rel=\"author\">menardcanadainc<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-16T16:59:56+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/300x225-pixels-Website-2.png\" class=\"attachment-full size-full wp-post-image\" alt=\"Taunton Road West, Whitby (ON)\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/300x225-pixels-Website-2-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/300x225-pixels-Website-2.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/residence-whitby-ontario\/\">Lotissement R\u00e9sidentiel: Whitby, Ontario<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/residence-whitby-ontario\/\" aria-label=\"Lotissement R\u00e9sidentiel: Whitby, Ontario\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/residence-whitby-ontario\/\" target=\"_self\">Lotissement R\u00e9sidentiel: Whitby, Ontario<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Station de traitement des eaux : Chilliwack, Colombie-Britannique<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/benzion\/\" rel=\"author\">Menard Canada<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-15T21:33:35+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/4-EDITED-scaled_300x225.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/4-EDITED-scaled_300x225-200x150.jpeg 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/4-EDITED-scaled_300x225.jpeg 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/station-traitement-eaux-chilliwack-colombie-britannique\/\">Station de traitement des eaux : Chilliwack, Colombie-Britannique<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/station-traitement-eaux-chilliwack-colombie-britannique\/\" aria-label=\"Station de traitement des eaux : Chilliwack, Colombie-Britannique\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/station-traitement-eaux-chilliwack-colombie-britannique\/\" target=\"_self\">Station de traitement des eaux : Chilliwack, Colombie-Britannique<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Station de pompage : Richmond, Colombie-Britannique<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/benzion\/\" rel=\"author\">Menard Canada<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-15T21:36:08+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"1036\" height=\"777\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/6-EDITED.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Pump Station - Richmond\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/6-EDITED-200x150.jpg 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/6-EDITED-400x300.jpg 400w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/6-EDITED-600x450.jpg 600w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/6-EDITED-800x600.jpg 800w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/6-EDITED.jpg 1036w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/station-de-pompage-richmond-colombie-britannique\/\">Station de pompage : Richmond, Colombie-Britannique<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/station-de-pompage-richmond-colombie-britannique\/\" aria-label=\"Station de pompage : Richmond, Colombie-Britannique\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/station-de-pompage-richmond-colombie-britannique\/\" target=\"_self\">Station de pompage : Richmond, Colombie-Britannique<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">YVR Airport: Richmond, Colombie Britannique<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/menardcanadainc\/\" rel=\"author\">menardcanadainc<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2025-09-10T20:18:09+02:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Sans-titre-9.png\" class=\"attachment-full size-full wp-post-image\" alt=\"YVR Airport - Pier D Expansion, Richmond, British Colombia\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Sans-titre-9-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Sans-titre-9.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/aeroport-yvr-richmond-colombie-britannique\/\">YVR Airport: Richmond, Colombie Britannique<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/aeroport-yvr-richmond-colombie-britannique\/\" aria-label=\"YVR Airport: Richmond, Colombie Britannique\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/aeroport-yvr-richmond-colombie-britannique\/\" target=\"_self\">YVR Airport: Richmond, Colombie Britannique<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Projet d&rsquo;expansion de Trans Mountain : Edmonton, Alberta<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/benzion\/\" rel=\"author\">Menard Canada<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-15T21:40:41+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/2-EDITED-1-scaled-1-e1663185304434.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/projet-expansion-trans-mountain\/\">Projet d&rsquo;expansion de Trans Mountain : Edmonton, Alberta<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/projet-expansion-trans-mountain\/\" aria-label=\"Projet d&rsquo;expansion de Trans Mountain : Edmonton, Alberta\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/projet-expansion-trans-mountain\/\" target=\"_self\">Projet d&rsquo;expansion de Trans Mountain : Edmonton, Alberta<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Mine: Malartic, Qu\u00e9bec<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/menardcanadainc\/\" rel=\"author\">menardcanadainc<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-16T16:37:41+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Sans-titre-8.png\" class=\"attachment-full size-full wp-post-image\" alt=\"Canadian Malartic Mine, Malartic, Qu\u00e9bec\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Sans-titre-8-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Sans-titre-8.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/mine-malartic-quebec\/\">Mine: Malartic, Qu\u00e9bec<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/mine-malartic-quebec\/\" aria-label=\"Mine: Malartic, Qu\u00e9bec\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/mine-malartic-quebec\/\" target=\"_self\">Mine: Malartic, Qu\u00e9bec<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Digue de Whale Tale : Amaruq, Nunavut<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/menardcanadainc\/\" rel=\"author\">menardcanadainc<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-05-02T22:21:23+02:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Sans-titre-7.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Sans-titre-7-200x150.png 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/Sans-titre-7.png 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/digue-whale-tale-amaruq-nunavut\/\">Digue de Whale Tale : Amaruq, Nunavut<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/digue-whale-tale-amaruq-nunavut\/\" aria-label=\"Digue de Whale Tale : Amaruq, Nunavut\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/digue-whale-tale-amaruq-nunavut\/\" target=\"_self\">Digue de Whale Tale : Amaruq, Nunavut<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Mines VALE Nickel : Sudbury, Ontario<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/menardcanadainc\/\" rel=\"author\">menardcanadainc<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-16T16:32:31+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/2-1-EDITED-scaled-e1663185424228.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/mines-vale-nickel-sudbury-ontario\/\">Mines VALE Nickel : Sudbury, Ontario<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/mines-vale-nickel-sudbury-ontario\/\" aria-label=\"Mines VALE Nickel : Sudbury, Ontario\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/mines-vale-nickel-sudbury-ontario\/\" target=\"_self\">Mines VALE Nickel : Sudbury, Ontario<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">Mine Wesdome Kiena : Val d&rsquo;or, Qu\u00e9bec<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/menardcanadainc\/\" rel=\"author\">menardcanadainc<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-11-16T16:49:32+01:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/1-1-EDITED-scaled-e1663185506844.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Wesdome mine\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/mine-wesdome-kiena-quebec\/\">Mine Wesdome Kiena : Val d&rsquo;or, Qu\u00e9bec<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/mine-wesdome-kiena-quebec\/\" aria-label=\"Mine Wesdome Kiena : Val d&rsquo;or, Qu\u00e9bec\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/mine-wesdome-kiena-quebec\/\" target=\"_self\">Mine Wesdome Kiena : Val d&rsquo;or, Qu\u00e9bec<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">B\u00e2timent de stockage d&rsquo;Hydro One : Dunnville, Ontario<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/benzion\/\" rel=\"author\">Menard Canada<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-05-02T22:14:02+02:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/WickDrains2.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/WickDrains2-200x150.jpg 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/WickDrains2.jpg 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/batiment-stockage-hydro-one\/\">B\u00e2timent de stockage d&rsquo;Hydro One : Dunnville, Ontario<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/batiment-stockage-hydro-one\/\" aria-label=\"B\u00e2timent de stockage d&rsquo;Hydro One : Dunnville, Ontario\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/batiment-stockage-hydro-one\/\" target=\"_self\">B\u00e2timent de stockage d&rsquo;Hydro One : Dunnville, Ontario<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><span class=\"entry-title rich-snippet-hidden\">B\u00e2timent industriel : B\u00e9cancour, Qu\u00e9bec<\/span><span class=\"vcard rich-snippet-hidden\"><span class=\"fn\"><a href=\"https:\/\/menardcanada.ca\/fr\/author\/benzion\/\" rel=\"author\">Menard Canada<\/a><\/span><\/span><span class=\"updated rich-snippet-hidden\">2023-05-02T22:10:28+02:00<\/span><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/20-1-1200x1600-1-1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/20-1-1200x1600-1-1-200x150.jpg 200w, https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2022\/08\/20-1-1200x1600-1-1.jpg 300w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 370px, (min-width: 712px) 555px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/innomalt-becancour-quebec\/\">B\u00e2timent industriel : B\u00e9cancour, Qu\u00e9bec<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/innomalt-becancour-quebec\/\" aria-label=\"B\u00e2timent industriel : B\u00e9cancour, Qu\u00e9bec\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<h4 class=\"fusion-carousel-title\"><a href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/innomalt-becancour-quebec\/\" target=\"_self\">B\u00e2timent industriel : B\u00e9cancour, Qu\u00e9bec<\/a><\/h4><div class=\"fusion-carousel-meta\"><a href=\"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/\" rel=\"tag\">Projets<\/a><\/div><\/div><\/div><\/div><div class=\"awb-swiper-button awb-swiper-button-prev\"><i class=\"awb-icon-angle-left\" aria-hidden=\"true\"><\/i><\/div><div class=\"awb-swiper-button awb-swiper-button-next\"><i class=\"awb-icon-angle-right\" aria-hidden=\"true\"><\/i><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4521,"featured_media":12714,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"footnotes":""},"portfolio_category":[266],"portfolio_skills":[],"portfolio_tags":[313],"class_list":["post-12541","avada_portfolio","type-avada_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-projets","portfolio_tags-batiments"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entrepot Ac\u00e9ricole: Plessisville, Qu\u00e9bec | Menard Canada<\/title>\n<meta name=\"description\" content=\"Vous voulez en savoir plus sur ce projet que nous avons r\u00e9alis\u00e9? D\u00e9couvrez comment nous avons aid\u00e9 d&#039;autres personnes \u00e0 am\u00e9liorer les conditions de leur sol.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/entrepot-acericole-plessisville-quebec\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entrepot Ac\u00e9ricole: Plessisville, Qu\u00e9bec | Menard Canada\" \/>\n<meta property=\"og:description\" content=\"Vous voulez en savoir plus sur ce projet que nous avons r\u00e9alis\u00e9? D\u00e9couvrez comment nous avons aid\u00e9 d&#039;autres personnes \u00e0 am\u00e9liorer les conditions de leur sol.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/entrepot-acericole-plessisville-quebec\/\" \/>\n<meta property=\"og:site_name\" content=\"Menard Canada\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-16T16:38:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/09\/Entrepot-Acericole_20220524-Grue-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/soil-expert-portfolio\\\/entrepot-acericole-plessisville-quebec\\\/\",\"url\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/soil-expert-portfolio\\\/entrepot-acericole-plessisville-quebec\\\/\",\"name\":\"Entrepot Ac\u00e9ricole: Plessisville, Qu\u00e9bec | Menard Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/soil-expert-portfolio\\\/entrepot-acericole-plessisville-quebec\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/soil-expert-portfolio\\\/entrepot-acericole-plessisville-quebec\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/menardcanada.ca\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2023\\\/09\\\/Entrepot-Acericole_20220524-Grue-scaled.jpg\",\"datePublished\":\"2023-09-19T18:10:06+00:00\",\"dateModified\":\"2023-11-16T16:38:59+00:00\",\"description\":\"Vous voulez en savoir plus sur ce projet que nous avons r\u00e9alis\u00e9? D\u00e9couvrez comment nous avons aid\u00e9 d'autres personnes \u00e0 am\u00e9liorer les conditions de leur sol.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/soil-expert-portfolio\\\/entrepot-acericole-plessisville-quebec\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/soil-expert-portfolio\\\/entrepot-acericole-plessisville-quebec\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/soil-expert-portfolio\\\/entrepot-acericole-plessisville-quebec\\\/#primaryimage\",\"url\":\"https:\\\/\\\/menardcanada.ca\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2023\\\/09\\\/Entrepot-Acericole_20220524-Grue-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/menardcanada.ca\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2023\\\/09\\\/Entrepot-Acericole_20220524-Grue-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/soil-expert-portfolio\\\/entrepot-acericole-plessisville-quebec\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/soil-expert-portfolio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Projets\",\"item\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/portfolio_category\\\/projets\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Entrep\u00f4t Ac\u00e9ricole: Plessisville, Qu\u00e9bec\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/\",\"name\":\"Menard Canada\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/#organization\",\"name\":\"Menard group, world specialist in ground improvement\",\"url\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/menardcanada.ca\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2021\\\/06\\\/MENARD-LOGO-icon-above-colour.png\",\"contentUrl\":\"https:\\\/\\\/menardcanada.ca\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2021\\\/06\\\/MENARD-LOGO-icon-above-colour.png\",\"width\":110,\"height\":82,\"caption\":\"Menard group, world specialist in ground improvement\"},\"image\":{\"@id\":\"https:\\\/\\\/menardcanada.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/menardcanada\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCdvM6StxaNiS1U1g8i7hYEw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entrepot Ac\u00e9ricole: Plessisville, Qu\u00e9bec | Menard Canada","description":"Vous voulez en savoir plus sur ce projet que nous avons r\u00e9alis\u00e9? D\u00e9couvrez comment nous avons aid\u00e9 d'autres personnes \u00e0 am\u00e9liorer les conditions de leur sol.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/entrepot-acericole-plessisville-quebec\/","og_locale":"fr_FR","og_type":"article","og_title":"Entrepot Ac\u00e9ricole: Plessisville, Qu\u00e9bec | Menard Canada","og_description":"Vous voulez en savoir plus sur ce projet que nous avons r\u00e9alis\u00e9? D\u00e9couvrez comment nous avons aid\u00e9 d'autres personnes \u00e0 am\u00e9liorer les conditions de leur sol.","og_url":"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/entrepot-acericole-plessisville-quebec\/","og_site_name":"Menard Canada","article_modified_time":"2023-11-16T16:38:59+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/09\/Entrepot-Acericole_20220524-Grue-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/entrepot-acericole-plessisville-quebec\/","url":"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/entrepot-acericole-plessisville-quebec\/","name":"Entrepot Ac\u00e9ricole: Plessisville, Qu\u00e9bec | Menard Canada","isPartOf":{"@id":"https:\/\/menardcanada.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/entrepot-acericole-plessisville-quebec\/#primaryimage"},"image":{"@id":"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/entrepot-acericole-plessisville-quebec\/#primaryimage"},"thumbnailUrl":"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/09\/Entrepot-Acericole_20220524-Grue-scaled.jpg","datePublished":"2023-09-19T18:10:06+00:00","dateModified":"2023-11-16T16:38:59+00:00","description":"Vous voulez en savoir plus sur ce projet que nous avons r\u00e9alis\u00e9? D\u00e9couvrez comment nous avons aid\u00e9 d'autres personnes \u00e0 am\u00e9liorer les conditions de leur sol.","breadcrumb":{"@id":"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/entrepot-acericole-plessisville-quebec\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/entrepot-acericole-plessisville-quebec\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/entrepot-acericole-plessisville-quebec\/#primaryimage","url":"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/09\/Entrepot-Acericole_20220524-Grue-scaled.jpg","contentUrl":"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2023\/09\/Entrepot-Acericole_20220524-Grue-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/entrepot-acericole-plessisville-quebec\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/menardcanada.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"https:\/\/menardcanada.ca\/fr\/soil-expert-portfolio\/"},{"@type":"ListItem","position":3,"name":"Projets","item":"https:\/\/menardcanada.ca\/fr\/portfolio_category\/projets\/"},{"@type":"ListItem","position":4,"name":"Entrep\u00f4t Ac\u00e9ricole: Plessisville, Qu\u00e9bec"}]},{"@type":"WebSite","@id":"https:\/\/menardcanada.ca\/fr\/#website","url":"https:\/\/menardcanada.ca\/fr\/","name":"Menard Canada","description":"","publisher":{"@id":"https:\/\/menardcanada.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/menardcanada.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/menardcanada.ca\/fr\/#organization","name":"Menard group, world specialist in ground improvement","url":"https:\/\/menardcanada.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/menardcanada.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2021\/06\/MENARD-LOGO-icon-above-colour.png","contentUrl":"https:\/\/menardcanada.ca\/wp-content\/uploads\/sites\/8\/2021\/06\/MENARD-LOGO-icon-above-colour.png","width":110,"height":82,"caption":"Menard group, world specialist in ground improvement"},"image":{"@id":"https:\/\/menardcanada.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/menardcanada","https:\/\/www.youtube.com\/channel\/UCdvM6StxaNiS1U1g8i7hYEw"]}]}},"_links":{"self":[{"href":"https:\/\/menardcanada.ca\/fr\/wp-json\/wp\/v2\/avada_portfolio\/12541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/menardcanada.ca\/fr\/wp-json\/wp\/v2\/avada_portfolio"}],"about":[{"href":"https:\/\/menardcanada.ca\/fr\/wp-json\/wp\/v2\/types\/avada_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/menardcanada.ca\/fr\/wp-json\/wp\/v2\/users\/4521"}],"replies":[{"embeddable":true,"href":"https:\/\/menardcanada.ca\/fr\/wp-json\/wp\/v2\/comments?post=12541"}],"version-history":[{"count":0,"href":"https:\/\/menardcanada.ca\/fr\/wp-json\/wp\/v2\/avada_portfolio\/12541\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/menardcanada.ca\/fr\/wp-json\/wp\/v2\/media\/12714"}],"wp:attachment":[{"href":"https:\/\/menardcanada.ca\/fr\/wp-json\/wp\/v2\/media?parent=12541"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/menardcanada.ca\/fr\/wp-json\/wp\/v2\/portfolio_category?post=12541"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/menardcanada.ca\/fr\/wp-json\/wp\/v2\/portfolio_skills?post=12541"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/menardcanada.ca\/fr\/wp-json\/wp\/v2\/portfolio_tags?post=12541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}